{"id":7873,"date":"2023-11-11T17:50:27","date_gmt":"2023-11-11T16:50:27","guid":{"rendered":"http:\/\/joelgirauddepute.fr\/?p=7873"},"modified":"2023-11-11T17:50:59","modified_gmt":"2023-11-11T16:50:59","slug":"commemoration-de-larmistice-du-11-novembre-1918","status":"publish","type":"post","link":"http:\/\/joelgirauddepute.fr\/index.php\/2023\/11\/11\/commemoration-de-larmistice-du-11-novembre-1918\/","title":{"rendered":"Comm\u00e9moration de l&rsquo;Armistice du 11 novembre 1918"},"content":{"rendered":"\n<p>Beaucoup de citoyens et de jeunes devant les monuments aux morts haut-alpins. Ici \u00e0 L&rsquo;Argenti\u00e8re avec le conseil municipal jeunes et la classe M\u00e9moire et Avenir du coll\u00e8ge des Giraudes. Un message de paix et d&rsquo;espoir en ce monde troubl\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/joelgirauddepute.fr\/wp-content\/uploads\/2023\/11\/photo_2023-11-11_12-31-20-1024x768.jpg\" alt=\"\" class=\"wp-image-7875\" srcset=\"http:\/\/joelgirauddepute.fr\/wp-content\/uploads\/2023\/11\/photo_2023-11-11_12-31-20-1024x768.jpg 1024w, http:\/\/joelgirauddepute.fr\/wp-content\/uploads\/2023\/11\/photo_2023-11-11_12-31-20-300x225.jpg 300w, http:\/\/joelgirauddepute.fr\/wp-content\/uploads\/2023\/11\/photo_2023-11-11_12-31-20-768x576.jpg 768w, http:\/\/joelgirauddepute.fr\/wp-content\/uploads\/2023\/11\/photo_2023-11-11_12-31-20-678x509.jpg 678w, http:\/\/joelgirauddepute.fr\/wp-content\/uploads\/2023\/11\/photo_2023-11-11_12-31-20-326x245.jpg 326w, http:\/\/joelgirauddepute.fr\/wp-content\/uploads\/2023\/11\/photo_2023-11-11_12-31-20-80x60.jpg 80w, http:\/\/joelgirauddepute.fr\/wp-content\/uploads\/2023\/11\/photo_2023-11-11_12-31-20.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Beaucoup de citoyens et de jeunes devant les monuments aux morts haut-alpins. Ici \u00e0 L&rsquo;Argenti\u00e8re avec le conseil municipal jeunes et la classe M\u00e9moire et <a class=\"mh-excerpt-more\" href=\"http:\/\/joelgirauddepute.fr\/index.php\/2023\/11\/11\/commemoration-de-larmistice-du-11-novembre-1918\/\" title=\"Comm\u00e9moration de l&rsquo;Armistice du 11 novembre 1918\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":7874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43],"tags":[],"class_list":["post-7873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-circo","category-hautes-alpes"],"jetpack_featured_media_url":"http:\/\/joelgirauddepute.fr\/wp-content\/uploads\/2023\/11\/photo_2023-11-11_16-47-19.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pabfdt-22Z","_links":{"self":[{"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/posts\/7873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/comments?post=7873"}],"version-history":[{"count":2,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/posts\/7873\/revisions"}],"predecessor-version":[{"id":7877,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/posts\/7873\/revisions\/7877"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/media\/7874"}],"wp:attachment":[{"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/media?parent=7873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/categories?post=7873"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/tags?post=7873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}