{"id":652,"date":"2017-10-10T14:30:50","date_gmt":"2017-10-10T12:30:50","guid":{"rendered":"http:\/\/joelgirauddepute.fr\/?p=652"},"modified":"2017-10-10T14:30:50","modified_gmt":"2017-10-10T12:30:50","slug":"gaz-de-schiste-charbon-hydrocarbures-liquides-et-gazeux-les-deputes-franchissent-une-etape-importante","status":"publish","type":"post","link":"http:\/\/joelgirauddepute.fr\/index.php\/2017\/10\/10\/gaz-de-schiste-charbon-hydrocarbures-liquides-et-gazeux-les-deputes-franchissent-une-etape-importante\/","title":{"rendered":"Gaz de schiste, charbon, hydrocarbures liquides et gazeux : Les d\u00e9put\u00e9s franchissent une \u00e9tape importante"},"content":{"rendered":"<p>L\u2019examen du projet de loi mettant fin \u00e0 la recherche ainsi qu\u2019\u00e0 l\u2019exploitation des hydrocarbures conventionnels et non conventionnels vient de s\u2019achever \u00e0 l\u2019Assembl\u00e9e nationale en premi\u00e8re lecture. Il constitue une \u00e9tape importante dans la mise en \u0153uvre du Plan Climat pr\u00e9sent\u00e9 le 6 juillet par Nicolas HULOT, Ministre de la Transition \u00e9cologique et solidaire.<\/p>\n<p>Le travail de Jo\u00ebl Giraud et de ses coll\u00e8gues d\u00e9put\u00e9s du groupe La R\u00e9publique En Marche a permis d\u2019am\u00e9liorer significativement le texte, notamment sur :<\/p>\n<ul>\n<li><strong>La question des hydrocarbures non conventionnels<\/strong> afin de s\u2019assurer qu\u2019en aucun cas on ne pourra, en France, exploiter un gisement de gaz de schiste ;<\/li>\n<li><strong>L\u2019interdiction du charbon et une clarification de la d\u00e9finition du gaz de mine<\/strong> pour interdire clairement l\u2019exploration et l\u2019exploitation du gaz de couche\u00a0;<\/li>\n<li><strong>Le renforcement de la transparence<\/strong> avec la mise en ligne de l\u2019ensemble des demandes et des titres d\u2019exploration et d\u2019exploitations d\u2019hydrocarbures liquides et gazeux, actualis\u00e9e chaque semestre\u00a0;<\/li>\n<li><strong>L\u2019encadrement du droit de suite<\/strong> afin de limiter l\u2019attribution de concessions accord\u00e9es \u00e0 l\u2019\u00e9ch\u00e9ance 2040.<\/li>\n<\/ul>\n<p>Le texte adopt\u00e9 est \u00e9quilibr\u00e9 et ambitieux car il permet d\u2019atteindre l\u2019objectif souhait\u00e9, \u00e0 savoir faire de la France le premier pays au monde \u00e0 programmer, pour 2040, la fin de l\u2019exploration et de l\u2019exploitation des hydrocarbures sur son territoire, tout en pr\u00e9servant les droits acquis et en laissant le temps aux territoires et entreprises concern\u00e9s d\u2019engager leur transition vers d\u2019autres activit\u00e9s.<\/p>\n<p><strong>Jo\u00ebl Giraud compte sur les s\u00e9nateurs pour conserver \u00e0 ce projet de loi le niveau d\u2019ambition \u00e9lev\u00e9 que l\u2019Assembl\u00e9e Nationale lui a donn\u00e9.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>L\u2019examen du projet de loi mettant fin \u00e0 la recherche ainsi qu\u2019\u00e0 l\u2019exploitation des hydrocarbures conventionnels et non conventionnels vient de s\u2019achever \u00e0 l\u2019Assembl\u00e9e nationale <a class=\"mh-excerpt-more\" href=\"http:\/\/joelgirauddepute.fr\/index.php\/2017\/10\/10\/gaz-de-schiste-charbon-hydrocarbures-liquides-et-gazeux-les-deputes-franchissent-une-etape-importante\/\" title=\"Gaz de schiste, charbon, hydrocarbures liquides et gazeux : Les d\u00e9put\u00e9s franchissent une \u00e9tape importante\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,29],"tags":[],"class_list":["post-652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communiques","category-developpement-durable"],"jetpack_featured_media_url":"http:\/\/joelgirauddepute.fr\/wp-content\/uploads\/2017\/10\/nicolas-hulot-.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pabfdt-aw","_links":{"self":[{"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/posts\/652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/comments?post=652"}],"version-history":[{"count":1,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/posts\/652\/revisions"}],"predecessor-version":[{"id":654,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/posts\/652\/revisions\/654"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/media\/653"}],"wp:attachment":[{"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/media?parent=652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/categories?post=652"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/joelgirauddepute.fr\/index.php\/wp-json\/wp\/v2\/tags?post=652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}